{"id":2173,"date":"2009-01-14T08:49:05","date_gmt":"2009-01-14T07:49:05","guid":{"rendered":"https:\/\/www.churbayportillo.com\/blog\/?p=2173"},"modified":"2023-02-21T13:13:00","modified_gmt":"2023-02-21T12:13:00","slug":"preparate-para-mas-multas-de-trafico","status":"publish","type":"post","link":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/","title":{"rendered":"Prep\u00e1rate para m\u00e1s multas de tr\u00e1fico"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2186 alignnone\" title=\"Multa de tr\u00e1fico\" src=\"https:\/\/www.churbayportillo.com\/blog\/wp-content\/uploads\/2009\/01\/multa.jpg\" alt=\"\" width=\"333\" height=\"243\" srcset=\"https:\/\/www.churbayportillo.com\/blog\/wp-content\/uploads\/2009\/01\/multa.jpg 333w, https:\/\/www.churbayportillo.com\/blog\/wp-content\/uploads\/2009\/01\/multa-300x218.jpg 300w\" sizes=\"auto, (max-width: 333px) 100vw, 333px\" \/><\/p>\n<p style=\"text-align: left;\">Un nuevo estudio confirma lo que ya todos sab\u00edamos: cuando los ingresos de las administraciones caen, suben las multas de tr\u00e1fico.<!--more--><\/p>\n<p style=\"text-align: left;\">La investigaci\u00f3n que se publicar\u00e1 en el pr\u00f3ximo n\u00famero del <a title=\"Journal of Law and Economics\" href=\"https:\/\/www.journals.uchicago.edu\/\">Journal of Law and Economics<\/a> ofrece la confirmaci\u00f3n estad\u00edstica de lo que la mayor\u00eda de los conductores pensamos: las multas de tr\u00e1fico son un buen m\u00e9todo de recaudaci\u00f3n.<\/p>\n<blockquote style=\"text-align: left;\"><p>Concretamente, una disminuci\u00f3n de un punto porcentual el a\u00f1o anterior en los ingresos del gobierno local se traduce en aproximadamente un 0,32 puntos porcentuales de aumento en el n\u00famero de infracciones de tr\u00e1nsito en el a\u00f1o siguiente, afirman los autores del estudio, Thomas Garrett y Gary Wagner.<\/p>\n<p>Hay muchas evidencias anecd\u00f3ticas de que los gobiernos locales usan las multas de tr\u00e1fico como medio de generaci\u00f3n de ingresos &#8230;, conten\u00fa\u00adan los autores. Nuestro trabajo proporciona la primera evidencia emp\u00edrica para apoyar este punto de vista &#8230;.<\/p><\/blockquote>\n<p style=\"text-align: left;\">La investigaci\u00f3n se llev\u00f3 a cabo con los datos de 96 condados de Carolina del Norte, entre los a\u00f1os 1990 y 2003, pero suena muy familiar.<\/p>\n<p style=\"text-align: left;\">As\u00ed que otra consecuencia de las crisis econ\u00f3mica ser\u00e1, probablemente, que tendremos m\u00e1s multas de tr\u00e1fico. \u00a1Prepara tu bolsillo y el de tu empresa!<\/p>\n<p style=\"text-align: left;\"><em>Rogamos a las administraciones espa\u00f1olas no realizar un estudio similar o tendr\u00e1n que multarnos m\u00e1s para pagarlo.<\/em><\/p>\n<p style=\"text-align: left;\">Foto: eflon\/Creative Commons.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuevo estudio confirma lo que ya todos sab\u00edamos: cuando los ingresos de las administraciones caen, suben las multas de tr\u00e1fico.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,11],"tags":[694],"class_list":["post-2173","post","type-post","status-publish","format-standard","hentry","category-general","category-pymes","tag-crisis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prep\u00e1rate para m\u00e1s multas de tr\u00e1fico - El Secreto de las Pymes que crecen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prep\u00e1rate para m\u00e1s multas de tr\u00e1fico - El Secreto de las Pymes que crecen\" \/>\n<meta property=\"og:description\" content=\"Un nuevo estudio confirma lo que ya todos sab\u00edamos: cuando los ingresos de las administraciones caen, suben las multas de tr\u00e1fico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/\" \/>\n<meta property=\"og:site_name\" content=\"El Secreto de las Pymes que crecen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/churbayportillo\" \/>\n<meta property=\"article:published_time\" content=\"2009-01-14T07:49:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-21T12:13:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.churbayportillo.com\/blog\/wp-content\/uploads\/2009\/01\/multa.jpg\" \/>\n<meta name=\"author\" content=\"Jorge Churba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elsecreto\" \/>\n<meta name=\"twitter:site\" content=\"@elsecreto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Churba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/\"},\"author\":{\"name\":\"Jorge Churba\",\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/#\\\/schema\\\/person\\\/327f5e9fbcbeeb46bb1a6a1b69a3136b\"},\"headline\":\"Prep\u00e1rate para m\u00e1s multas de tr\u00e1fico\",\"datePublished\":\"2009-01-14T07:49:05+00:00\",\"dateModified\":\"2023-02-21T12:13:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/\"},\"wordCount\":247,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/wp-content\\\/uploads\\\/2009\\\/01\\\/multa.jpg\",\"keywords\":[\"Crisis\"],\"articleSection\":[\"General\",\"Pymes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/\",\"url\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/\",\"name\":\"Prep\u00e1rate para m\u00e1s multas de tr\u00e1fico - El Secreto de las Pymes que crecen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/wp-content\\\/uploads\\\/2009\\\/01\\\/multa.jpg\",\"datePublished\":\"2009-01-14T07:49:05+00:00\",\"dateModified\":\"2023-02-21T12:13:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/wp-content\\\/uploads\\\/2009\\\/01\\\/multa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/wp-content\\\/uploads\\\/2009\\\/01\\\/multa.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/2009\\\/01\\\/14\\\/preparate-para-mas-multas-de-trafico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prep\u00e1rate para m\u00e1s multas de tr\u00e1fico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/\",\"name\":\"El Secreto de las Pymes que crecen\",\"description\":\"Informaci\u00f3n y consejos para vender m\u00e1s\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/#organization\",\"name\":\"El Secreto de las Pymes que crecen\",\"url\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logo.png\",\"width\":599,\"height\":109,\"caption\":\"El Secreto de las Pymes que crecen\"},\"image\":{\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/churbayportillo\",\"https:\\\/\\\/x.com\\\/elsecreto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/#\\\/schema\\\/person\\\/327f5e9fbcbeeb46bb1a6a1b69a3136b\",\"name\":\"Jorge Churba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5f9205dc97a66e1143b707b76fe364da0a694698284e0bc4f5629e814e5ee66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5f9205dc97a66e1143b707b76fe364da0a694698284e0bc4f5629e814e5ee66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5f9205dc97a66e1143b707b76fe364da0a694698284e0bc4f5629e814e5ee66?s=96&d=mm&r=g\",\"caption\":\"Jorge Churba\"},\"description\":\"Me comunico, luego existo. Autor del Diccionario Pr\u00e1ctico de Internet para Emprendedores. Fundador de Churba &amp; Portillo y trabajador en Internet. S\u00edgueme en Twitter\",\"sameAs\":[\"https:\\\/\\\/www.churbayportillo.com\\\/blog\"],\"url\":\"https:\\\/\\\/www.churbayportillo.com\\\/blog\\\/author\\\/jorge\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prep\u00e1rate para m\u00e1s multas de tr\u00e1fico - El Secreto de las Pymes que crecen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/","og_locale":"es_ES","og_type":"article","og_title":"Prep\u00e1rate para m\u00e1s multas de tr\u00e1fico - El Secreto de las Pymes que crecen","og_description":"Un nuevo estudio confirma lo que ya todos sab\u00edamos: cuando los ingresos de las administraciones caen, suben las multas de tr\u00e1fico.","og_url":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/","og_site_name":"El Secreto de las Pymes que crecen","article_publisher":"https:\/\/www.facebook.com\/churbayportillo","article_published_time":"2009-01-14T07:49:05+00:00","article_modified_time":"2023-02-21T12:13:00+00:00","og_image":[{"url":"https:\/\/www.churbayportillo.com\/blog\/wp-content\/uploads\/2009\/01\/multa.jpg","type":"","width":"","height":""}],"author":"Jorge Churba","twitter_card":"summary_large_image","twitter_creator":"@elsecreto","twitter_site":"@elsecreto","twitter_misc":{"Escrito por":"Jorge Churba","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/#article","isPartOf":{"@id":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/"},"author":{"name":"Jorge Churba","@id":"https:\/\/www.churbayportillo.com\/blog\/#\/schema\/person\/327f5e9fbcbeeb46bb1a6a1b69a3136b"},"headline":"Prep\u00e1rate para m\u00e1s multas de tr\u00e1fico","datePublished":"2009-01-14T07:49:05+00:00","dateModified":"2023-02-21T12:13:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/"},"wordCount":247,"commentCount":2,"publisher":{"@id":"https:\/\/www.churbayportillo.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.churbayportillo.com\/blog\/wp-content\/uploads\/2009\/01\/multa.jpg","keywords":["Crisis"],"articleSection":["General","Pymes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/","url":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/","name":"Prep\u00e1rate para m\u00e1s multas de tr\u00e1fico - El Secreto de las Pymes que crecen","isPartOf":{"@id":"https:\/\/www.churbayportillo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/#primaryimage"},"image":{"@id":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.churbayportillo.com\/blog\/wp-content\/uploads\/2009\/01\/multa.jpg","datePublished":"2009-01-14T07:49:05+00:00","dateModified":"2023-02-21T12:13:00+00:00","breadcrumb":{"@id":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/#primaryimage","url":"https:\/\/www.churbayportillo.com\/blog\/wp-content\/uploads\/2009\/01\/multa.jpg","contentUrl":"https:\/\/www.churbayportillo.com\/blog\/wp-content\/uploads\/2009\/01\/multa.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.churbayportillo.com\/blog\/2009\/01\/14\/preparate-para-mas-multas-de-trafico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.churbayportillo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Prep\u00e1rate para m\u00e1s multas de tr\u00e1fico"}]},{"@type":"WebSite","@id":"https:\/\/www.churbayportillo.com\/blog\/#website","url":"https:\/\/www.churbayportillo.com\/blog\/","name":"El Secreto de las Pymes que crecen","description":"Informaci\u00f3n y consejos para vender m\u00e1s","publisher":{"@id":"https:\/\/www.churbayportillo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.churbayportillo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.churbayportillo.com\/blog\/#organization","name":"El Secreto de las Pymes que crecen","url":"https:\/\/www.churbayportillo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.churbayportillo.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.churbayportillo.com\/blog\/wp-content\/uploads\/2021\/12\/logo.png","contentUrl":"https:\/\/www.churbayportillo.com\/blog\/wp-content\/uploads\/2021\/12\/logo.png","width":599,"height":109,"caption":"El Secreto de las Pymes que crecen"},"image":{"@id":"https:\/\/www.churbayportillo.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/churbayportillo","https:\/\/x.com\/elsecreto"]},{"@type":"Person","@id":"https:\/\/www.churbayportillo.com\/blog\/#\/schema\/person\/327f5e9fbcbeeb46bb1a6a1b69a3136b","name":"Jorge Churba","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c5f9205dc97a66e1143b707b76fe364da0a694698284e0bc4f5629e814e5ee66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5f9205dc97a66e1143b707b76fe364da0a694698284e0bc4f5629e814e5ee66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5f9205dc97a66e1143b707b76fe364da0a694698284e0bc4f5629e814e5ee66?s=96&d=mm&r=g","caption":"Jorge Churba"},"description":"Me comunico, luego existo. Autor del Diccionario Pr\u00e1ctico de Internet para Emprendedores. Fundador de Churba &amp; Portillo y trabajador en Internet. S\u00edgueme en Twitter","sameAs":["https:\/\/www.churbayportillo.com\/blog"],"url":"https:\/\/www.churbayportillo.com\/blog\/author\/jorge\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":19824,"url":"https:\/\/www.churbayportillo.com\/blog\/2012\/12\/04\/la-irresistible-ascension-del-movil\/","url_meta":{"origin":2173,"position":0},"title":"La irresistible ascensi\u00f3n del m\u00f3vil","author":"Jorge Churba","date":"4 diciembre 2012","format":false,"excerpt":"Una imagen vale por mil palabras, por eso este gr\u00e1fico lo dice todo: cada d\u00eda m\u00e1s gente en m\u00e1s lugares usa m\u00e1s dispositivos m\u00f3viles -tablets, smartphones, etc- para navegar por Internet. Lo importante, m\u00e1s que la cifra de un 13% del tr\u00e1fico global de Internet, es la tendencia ascendente que\u2026","rel":"","context":"En \u00abComercio electr\u00f3nico\u00bb","block_context":{"text":"Comercio electr\u00f3nico","link":"https:\/\/www.churbayportillo.com\/blog\/category\/comercio-electronico\/"},"img":{"alt_text":"Gr\u00e1fica del tr\u00e1fico de Internet desde m\u00f3vil","src":"https:\/\/i0.wp.com\/screto.s3.amazonaws.com\/uploads\/2012\/12\/grafica-internet-movil.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":13208,"url":"https:\/\/www.churbayportillo.com\/blog\/2011\/05\/03\/20-millones-para-jovenes-emprendedores\/","url_meta":{"origin":2173,"position":1},"title":"20 millones para j\u00f3venes emprendedores","author":"Jorge Churba","date":"3 mayo 2011","format":false,"excerpt":"Ya est\u00e1 aprobada una l\u00ednea de financiaci\u00f3n de 20 millones de euros destinada a favorecer la puesta en marcha de proyectos empresariales promovidos por j\u00f3venes emprendedores. Est\u00e1 dirigida a pymes de al menos un a\u00f1o de vida formadas mayoritariamente por empresarios de hasta 35 a\u00f1os. Habr\u00e1 pr\u00e9stamos de un importe\u2026","rel":"","context":"En \u00abEmprendedores\u00bb","block_context":{"text":"Emprendedores","link":"https:\/\/www.churbayportillo.com\/blog\/category\/emprendedores\/"},"img":{"alt_text":"Firma","src":"https:\/\/i0.wp.com\/screto.s3.amazonaws.com\/uploads\/2011\/05\/firma.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9915,"url":"https:\/\/www.churbayportillo.com\/blog\/2010\/07\/02\/los-envios-el-gran-problema-del-comercio-electronico\/","url_meta":{"origin":2173,"position":2},"title":"Los env\u00edos, el gran problema del comercio electr\u00f3nico","author":"Jorge Churba","date":"2 julio 2010","format":false,"excerpt":"Cuando abordamos con un cliente la creaci\u00f3n de una tienda on line siempre le advertimos sobre la importancia de los env\u00edos. Conseguir que sean r\u00e1pidos y a bajo coste es fundamental. El \u00cdndice eEspa\u00f1a 2010, que acaba de presentar la Fundaci\u00f3n Orange, confirma esta percepci\u00f3n. De hecho, el principal problema\u2026","rel":"","context":"En \u00abComercio electr\u00f3nico\u00bb","block_context":{"text":"Comercio electr\u00f3nico","link":"https:\/\/www.churbayportillo.com\/blog\/category\/comercio-electronico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/screto.s3.amazonaws.com\/uploads\/2010\/07\/carro-compra.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":711,"url":"https:\/\/www.churbayportillo.com\/blog\/2008\/10\/23\/corrupcion\/","url_meta":{"origin":2173,"position":3},"title":"Corrupci\u00f3n","author":"Jorge Churba","date":"23 octubre 2008","format":false,"excerpt":"https:\/\/www.youtube.com\/watch?v=T89hYePmAHw En el v\u00eddeo vemos el caso de corrupci\u00f3n del d\u00eda: el presunto soborno al concejal independiente del Ayuntamiento de San Fulgencio (Alicante). Un reciente estudio dice que estos casos abundan. El 32% de los directivos espa\u00f1oles dice haber perdido un negocio por negarse a pagar un soborno frente a\u2026","rel":"","context":"En \u00abGeneral\u00bb","block_context":{"text":"General","link":"https:\/\/www.churbayportillo.com\/blog\/category\/general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/T89hYePmAHw\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10071,"url":"https:\/\/www.churbayportillo.com\/blog\/2010\/07\/14\/errores-en-correos-electronicos-que-pueden-costar-60-000e\/","url_meta":{"origin":2173,"position":4},"title":"Errores en correos electr\u00f3nicos que pueden costar 60.000\u20ac","author":"Jorge Churba","date":"14 julio 2010","format":false,"excerpt":"Enviar un mailing en el que cualquiera de los destinatarios pueda ver las direcciones de correo electr\u00f3nico de los dem\u00e1s, puede costarte muy caro. \u00a1Nada menos que 60.000\u20ac! Porque si lo haces estas revelando datos privados e incumpliendo la Ley Org\u00e1nica de Protecci\u00f3n de Datos (LOPD). Por ahora, no conocemos\u2026","rel":"","context":"En \u00abBranding\u00bb","block_context":{"text":"Branding","link":"https:\/\/www.churbayportillo.com\/blog\/category\/branding\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/screto.s3.amazonaws.com\/uploads\/2010\/07\/correo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14302,"url":"https:\/\/www.churbayportillo.com\/blog\/2011\/08\/10\/internet-posicionamiento-vs-publicidad\/","url_meta":{"origin":2173,"position":5},"title":"Internet: posicionamiento vs. publicidad","author":"Jorge Churba","date":"10 agosto 2011","format":false,"excerpt":"Dos fuentes fundamentales para obtener tr\u00e1fico para nuestra web son el posicionamiento org\u00e1nico y las campa\u00f1as de publicidad en Google AdWords, pero \u00bfhay competencia entre ambas? \u00bfMe interesa invertir al mismo tiempo en publicidad y en posicionamiento? \u00bfQu\u00e9 pasa si dejo de anunciarme? \u00bfConseguir\u00e9 con el posicionamiento org\u00e1nico reemplazar las\u2026","rel":"","context":"En \u00abBlogs\u00bb","block_context":{"text":"Blogs","link":"https:\/\/www.churbayportillo.com\/blog\/category\/blogs\/"},"img":{"alt_text":"Posicionamiento-AdWords","src":"https:\/\/i0.wp.com\/screto.s3.amazonaws.com\/uploads\/2011\/08\/Posicionamiento-AdWords.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.churbayportillo.com\/blog\/wp-json\/wp\/v2\/posts\/2173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.churbayportillo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.churbayportillo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.churbayportillo.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.churbayportillo.com\/blog\/wp-json\/wp\/v2\/comments?post=2173"}],"version-history":[{"count":0,"href":"https:\/\/www.churbayportillo.com\/blog\/wp-json\/wp\/v2\/posts\/2173\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.churbayportillo.com\/blog\/wp-json\/wp\/v2\/media?parent=2173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.churbayportillo.com\/blog\/wp-json\/wp\/v2\/categories?post=2173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.churbayportillo.com\/blog\/wp-json\/wp\/v2\/tags?post=2173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}